{"id":12596,"date":"2024-08-06T21:43:07","date_gmt":"2024-08-07T00:43:07","guid":{"rendered":"https:\/\/ipatingafc.com.br\/index.php\/2024\/08\/06\/165-mil-alunos-farao-provas-para-vaga-em-competicao\/"},"modified":"2024-08-06T21:43:07","modified_gmt":"2024-08-07T00:43:07","slug":"165-mil-alunos-farao-provas-para-vaga-em-competicao","status":"publish","type":"post","link":"https:\/\/ipatingafc.com.br\/index.php\/2024\/08\/06\/165-mil-alunos-farao-provas-para-vaga-em-competicao\/","title":{"rendered":"16,5 mil alunos far\u00e3o provas para vaga em competi\u00e7\u00e3o"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.saopaulo.sp.gov.br\/wp-content\/uploads\/2024\/02\/53349767717_3c789305c3_k.jpg\" \/><\/p>\n<div id=\"\">&#13;<br \/>\n                                <!-- Title -->&#13;<br \/>\n                                &#13;<br \/>\n&#13;<br \/>\n                                <!-- Excerpt -->&#13;<\/p>\n<p class=\"excerpt\">Avalia\u00e7\u00e3o d\u00e1 acesso a 225 vagas em aulas intensivas e classifica\u00e7\u00e3o para a Olimp\u00edada Brasileira de Matem\u00e1tica<\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n                                &#13;\n                            <\/p><\/div>\n<div id=\"\">&#13;<\/p>\n<p><iframe loading=\"lazy\" title=\"Olimp\u00edada de Matem\u00e1tica: 16,5 mil estudantes de SP concorrem vaga em competi\u00e7\u00e3o nacional by Governo do Estado de S\u00e3o Paulo\" width=\"587\" height=\"330\" scrolling=\"no\" frameborder=\"no\" src=\"https:\/\/w.soundcloud.com\/player\/?visual=true&amp;url=https%3A%2F%2Fapi.soundcloud.com%2Ftracks%2F1890524574&amp;show_artwork=true&amp;maxheight=330&amp;maxwidth=587\"><\/iframe><\/p>\n<p>Mais de 16 mil alunos medalhistas de ouro da Olimp\u00edada de Matem\u00e1tica das Escolas Estaduais de S\u00e3o Paulo participam de uma prova classificat\u00f3ria para garantir vaga na Olimp\u00edada Brasileira de Matem\u00e1tica (OBM). A avalia\u00e7\u00e3o ser\u00e1 aplicada nesta quarta-feira (07) pela Secretaria da Educa\u00e7\u00e3o do Estado de S\u00e3o Paulo (Seduc-SP). O objetivo \u00e9 chegar a 225 estudantes que representar\u00e3o a rede estadual na competi\u00e7\u00e3o nacional.<\/p>\n<p>A avalia\u00e7\u00e3o ser\u00e1 aplicada durante o hor\u00e1rio de aulas. Os primeiros colocados ser\u00e3o premiados com medalhas de ouro, prata e bronze. Com base nesse resultado, os medalhistas de ouro ser\u00e3o beneficiados com aulas online, ministradas por especialistas em Olimp\u00edada Brasileira de Matem\u00e1tica.<\/p>\n<p>\u201cDos 1.935 alunos premiados, 225 ser\u00e3o medalhistas de ouro, que receber\u00e3o o convite para fazer a Olimp\u00edada Brasileira de Matem\u00e1tica. Sendo que, entre agosto e outubro, ser\u00e1 oferecido um treinamento para essa mesma OBM. As aulas da plataforma acontecer\u00e3o no contraturno e estar\u00e3o dispon\u00edveis para os nossos alunos de ouro, mas tamb\u00e9m os alunos de prata e bronze\u201d, explica o coordenador de olimp\u00edadas da Educa\u00e7\u00e3o, Roberto Serra Campos.<\/p>\n<p>O objetivo \u00e9 que esses alunos premiados com prata e bronze tenham mais uma ferramenta de aprendizado da disciplina e se aproximem de futuras chances para conquista do ouro. <span style=\"font-weight: 400;\">A ferramenta de prepara\u00e7\u00e3o, a <\/span><i><span style=\"font-weight: 400;\">Starboard Science, <\/span><\/i><span style=\"font-weight: 400;\">ser\u00e1 disponibilizada aos estudantes por meio de parceria sem custos \u00e0 Educa\u00e7\u00e3o do Estado, \u00e0s escolas, ou aos selecionados. A prepara\u00e7\u00e3o para a OBM, no formato online, acontecer\u00e1 no contraturno das aulas de cada estudante, e poder\u00e1 ser acessada de qualquer lugar com acesso \u00e0 internet, inclusive das escolas estaduais.<\/span><\/p>\n<p>\u00a0<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#13; &#13; &#13; &#13; &#13; Avalia\u00e7\u00e3o d\u00e1 acesso a 225 vagas em aulas intensivas e&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-12596","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12596"}],"version-history":[{"count":0,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12596\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}