{"id":13624,"date":"2024-09-10T00:50:36","date_gmt":"2024-09-10T03:50:36","guid":{"rendered":"https:\/\/ipatingafc.com.br\/index.php\/2024\/09\/10\/agencia-minas-gerais-mg-transplantes-realiza-evento-para-ampliar-busca-ativa-de-potenciais-doadores-de-orgaos\/"},"modified":"2024-09-10T00:50:36","modified_gmt":"2024-09-10T03:50:36","slug":"agencia-minas-gerais-mg-transplantes-realiza-evento-para-ampliar-busca-ativa-de-potenciais-doadores-de-orgaos","status":"publish","type":"post","link":"https:\/\/ipatingafc.com.br\/index.php\/2024\/09\/10\/agencia-minas-gerais-mg-transplantes-realiza-evento-para-ampliar-busca-ativa-de-potenciais-doadores-de-orgaos\/","title":{"rendered":"Ag\u00eancia Minas Gerais | MG Transplantes realiza evento para ampliar busca ativa de potenciais doadores de \u00f3rg\u00e3os"},"content":{"rendered":"<p><\/p>\n<div>\n<section class=\"news-related \/ col-md-4 col-lg-3 \/ margin-md-bottom-2 margin-left-1 \/ pull-right \/ hidden-xs hidden-sm\">\n<header>\n<p class=\"text-title-section \/ margin-bottom-1\">Relacionadas<\/p>\n<\/header>\n<p>\t\t\t\t\t\t\t<main><\/p>\n<hr class=\"row margin-md-bottom-2\"\/>\n<hr class=\"row margin-md-bottom-2\"\/>\n\t\t\t\t\t\t\t<\/main><br \/>\n\t\t\t\t\t\t<\/section>\n<p>Buscando a sensibiliza\u00e7\u00e3o dos profissionais de sa\u00fade para a import\u00e2ncia das Comiss\u00f5es Intra-Hospitalares de Doa\u00e7\u00e3o de \u00d3rg\u00e3os e Tecidos para Transplante, o MG Transplantes, da Funda\u00e7\u00e3o Hospitalar do Estado de Minas Gerais (Fhemig), realizou no audit\u00f3rio do Hospital Jo\u00e3o XXIII na sexta-feira (6\/9), o 3\u00ba Simp\u00f3sio das CIHDOTTSs da Regi\u00e3o Metropolitana.<\/p>\n<p>O evento, voltado para comiss\u00f5es j\u00e1 formadas e equipes interessadas em melhorar o seu servi\u00e7o de notifica\u00e7\u00f5es, contou com representantes de diversos hospitais de Belo Horizonte e de outras cidades do estado.<\/p>\n<p>As Comiss\u00f5es Intra-hospitalares de Doa\u00e7\u00e3o de \u00d3rg\u00e3os e Tecidos para Transplante (CIHDOTTSs) t\u00eam a fun\u00e7\u00e3o de realizar a busca ativa de potenciais doadores nas unidades hospitalares, auxiliar na condu\u00e7\u00e3o do protocolo e acompanhar todo o processo junto \u00e0s Organiza\u00e7\u00f5es de Procura de \u00d3rg\u00e3os (OPOs), garantindo que tudo ocorra dentro da legalidade e com seguran\u00e7a.<\/p>\n<p>As comiss\u00f5es tamb\u00e9m devem se envolver na capacita\u00e7\u00e3o cont\u00ednua dos profissionais de sa\u00fade, para garantir que estejam preparados para identificar e lidar adequadamente com situa\u00e7\u00f5es de potencial doa\u00e7\u00e3o, al\u00e9m de seguir os protocolos legais e \u00e9ticos necess\u00e1rios.<\/p>\n<p>\u201cAs CIHDOTTs s\u00e3o as menores c\u00e9lulas do Sistema Nacional de Transplantes, mas as mais importantes. Elas \u00e9 que v\u00e3o comunicar com as Organiza\u00e7\u00f5es de Procura de \u00d3rg\u00e3os a exist\u00eancia de um doador, seja de cora\u00e7\u00e3o parado para doa\u00e7\u00e3o de tecido, seja de morte encef\u00e1lica para doa\u00e7\u00e3o de m\u00faltiplos \u00f3rg\u00e3os, para iniciar o processo de doa\u00e7\u00e3o. Sem essas comiss\u00f5es, n\u00e3o \u00e9 poss\u00edvel fazer nada\u201d, explica o diretor do MG Transplantes, Omar Lopes Can\u00e7ado.<\/p>\n<p>O diretor apresentou aos participantes a estrutura\u00e7\u00e3o das comiss\u00f5es no processo de doa\u00e7\u00e3o de \u00f3rg\u00e3os e a situa\u00e7\u00e3o atual dos transplantes em Minas Gerais e no Brasil.<\/p>\n<p><strong>Import\u00e2ncia<\/strong><\/p>\n<p>De acordo com a gerente administrativa do MG Transplantes, Edil\u00e9ia Gon\u00e7alves, que falou sobre a estrutura, cadastro e incentivos governamentais para as comiss\u00f5es atuantes, o simp\u00f3sio \u00e9 relevante n\u00e3o somente para a qualifica\u00e7\u00e3o das comiss\u00f5es j\u00e1 existentes, como tamb\u00e9m para a atualiza\u00e7\u00e3o das informa\u00e7\u00f5es relacionadas \u00e0 pol\u00edtica de doa\u00e7\u00e3o de \u00f3rg\u00e3os e tecidos.<\/p>\n<p>\u201cComo estamos em um m\u00eas de campanhas intensificadas (Setembro Verde), o simp\u00f3sio \u00e9 mais uma forma de divulgar a causa e impactar no aumento das doa\u00e7\u00f5es, que \u00e9 o nosso maior objetivo\u201d, avalia.<\/p>\n<p>Para Omar Can\u00e7ado, um dos principais objetivos dos encontros \u00e9 conhecer os representantes dos hospitais e ficar mais pr\u00f3ximos das comiss\u00f5es, para que o sistema funcione melhor.<\/p>\n<p>\u201cNesse momento conseguimos reunir os maiores hospitais da Regi\u00e3o Metropolitana de Belo Horizonte (RMBH) e tirar d\u00favidas sobre todo o processo de doa\u00e7\u00e3o de transplantes, na expectativa de aumentar o n\u00famero de notifica\u00e7\u00f5es e reduzir a fila de espera\u201d, afirma.<\/p>\n<p><strong>Capacita\u00e7\u00e3o<\/strong><\/p>\n<p>Conversar com uma fam\u00edlia que acabou de receber a not\u00edcia da perda de um ente querido e perguntar se ela autoriza a doa\u00e7\u00e3o dos \u00f3rg\u00e3os da pessoa n\u00e3o \u00e9 uma tarefa f\u00e1cil. \u00c9 por isso que \u00e9 preciso treinamento constante dos profissionais atuantes para realizarem esta abordagem.<\/p>\n<p>As equipes multidisciplinares das CIHDOTTSs, al\u00e9m de dominarem toda a parte te\u00f3rica e pr\u00e1tica do processo de doa\u00e7\u00e3o e protocolo de determina\u00e7\u00e3o de morte encef\u00e1lica, devem desenvolver habilidades de comunica\u00e7\u00e3o e acolhimento nos processos de entrevista familiar, suficientes para demonstrar empatia, esclarecer todas as d\u00favidas da fam\u00edlia e dar a ela seguran\u00e7a para dizer sim.<\/p>\n<p>\u201cAs Centrais Estaduais de Transplantes, como a de Minas Gerais, constantemente realizam cursos espec\u00edficos para manter os profissionais de sa\u00fade atualizados, como o de Comunica\u00e7\u00e3o Cr\u00edtica, e as OPOs desenvolvem o programa de educa\u00e7\u00e3o continuada em cada \u00e1rea de abrang\u00eancia, com orienta\u00e7\u00f5es, treinamentos presenciais e apoio local\u201d, explica Edil\u00e9ia Gon\u00e7alves.<\/p>\n<p><strong>Crit\u00e9rios<\/strong><\/p>\n<p>Qualquer hospital pode ter CIHDOTTs, que s\u00e3o classificadas pelo n\u00famero de \u00f3bitos da unidade, a sua especialidade, entre outros crit\u00e9rios estabelecidos.<\/p>\n<p>Independentemente de sua classifica\u00e7\u00e3o, o importante \u00e9 que haja uma equipe voltada para os pacientes poss\u00edveis doadores, que observe qual evolui para a morte encef\u00e1lica, e fa\u00e7a todo o acompanhamento da equipe assistencial.<\/p>\n<p>\u201cA cria\u00e7\u00e3o das CIHDOTTs ser\u00e1 obrigat\u00f3ria nos hospitais p\u00fablicos, privados e filantr\u00f3picos que se enquadrem nos perfis espec\u00edficos determinados pela legisla\u00e7\u00e3o\u201d, enfatiza Edil\u00e9ia.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Relacionadas Buscando a sensibiliza\u00e7\u00e3o dos profissionais de sa\u00fade para a import\u00e2ncia das Comiss\u00f5es Intra-Hospitalares de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-13624","post","type-post","status-publish","format-standard","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13624"}],"version-history":[{"count":0,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13624\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}