{"id":25201,"date":"2025-06-30T19:38:51","date_gmt":"2025-06-30T22:38:51","guid":{"rendered":"https:\/\/ipatingafc.com.br\/index.php\/2025\/06\/30\/comlurb-convoca-400-garis-aprovados-em-processo-seletivo-prefeitura-da-cidade-do-rio-de-janeiro\/"},"modified":"2025-06-30T19:38:51","modified_gmt":"2025-06-30T22:38:51","slug":"comlurb-convoca-400-garis-aprovados-em-processo-seletivo-prefeitura-da-cidade-do-rio-de-janeiro","status":"publish","type":"post","link":"https:\/\/ipatingafc.com.br\/index.php\/2025\/06\/30\/comlurb-convoca-400-garis-aprovados-em-processo-seletivo-prefeitura-da-cidade-do-rio-de-janeiro\/","title":{"rendered":"Comlurb convoca 400 garis aprovados em processo seletivo &#8211; Prefeitura da Cidade do Rio de Janeiro"},"content":{"rendered":"<p><\/p>\n<div wp_automatic_readability=\"98.928091872792\">\n<div class=\"image-post\" wp_automatic_readability=\"33\">\n                     Contratos t\u00eam prazo de um ano, podendo ser prorrogados at\u00e9 cinco vezes &#8211; F\u00e1bio Motta\/Prefeitura                  <\/div>\n<p>O prefeito Eduardo Paes, o vice-prefeito Eduardo Cavaliere, o presidente da Comlurb, Jorge Arraes, e o secret\u00e1rio de Conserva\u00e7\u00e3o e Servi\u00e7os P\u00fablicos, Diego Vaz, participaram nesta segunda-feira (30\/06) na Cidade das Artes, na Barra da Tijuca, da cerim\u00f4nia de convoca\u00e7\u00e3o dos 400 novos garis aprovados em processo seletivo. Os profissionais selecionados ser\u00e3o admitidos por tempo determinado, com base na Lei Municipal n\u00ba 8.666\/2024, para atender a necessidades tempor\u00e1rias de interesse p\u00fablico. O v\u00ednculo inicial ter\u00e1 dura\u00e7\u00e3o de um ano, com possibilidade de prorroga\u00e7\u00e3o por at\u00e9 cinco vezes. As vagas ser\u00e3o preenchidas de forma imediata.<\/p>\n<p>Ao longo desta segunda, das 9h \u00e0s 16h, os novos garis receberam orienta\u00e7\u00f5es sobre as \u00e1reas em que ir\u00e3o atuar, com destaque para seguran\u00e7a do trabalho, rotinas operacionais da limpeza urbana e outros temas relevantes.<\/p>\n<blockquote wp_automatic_readability=\"10\">\n<p>\u2013 Queria dar as boas-vindas a voc\u00eas. Est\u00e3o entrando numa Companhia da qual a gente tem muito orgulho: a Comlurb. Toda pesquisa mostra que \u00e9 o servi\u00e7o p\u00fablico com que o carioca mais se identifica. A Comlurb \u00e9 a cara da cidade. E, a partir de agora, voc\u00eas representam isso nas ruas \u2013 declarou o prefeito Eduardo Paes.<\/p>\n<\/blockquote>\n<p>Em seguida, o vice-prefeito Eduardo Cavaliere incentivou os novos colaboradores a se dedicarem com orgulho \u00e0 miss\u00e3o de cuidar da cidade.<\/p>\n<blockquote wp_automatic_readability=\"8\">\n<p>\u2013 O cart\u00e3o de visita da Prefeitura do Rio \u00e9 a Comlurb. E o mais bonito desse cart\u00e3o \u00e9 o sorriso de voc\u00eas. Caiam dentro, trabalhem muito. A gente tem muito orgulho de voc\u00eas. Mantenham o sorriso no rosto e a alegria de fazer parte desse time. Voc\u00eas nos representam \u2013 completou.<\/p>\n<\/blockquote>\n<p>O edital do processo seletivo foi publicado em 3 de junho. Entre os crit\u00e9rios exigidos estavam: idade entre 18 e 50 anos; escolaridade m\u00ednima equivalente \u00e0 5\u00aa s\u00e9rie completa do Ensino Fundamental; e aptid\u00e3o f\u00edsica compat\u00edvel com as atividades a serem desempenhadas. Os candidatos puderam obter um ponto adicional ao comprovar, no m\u00ednimo, um ano completo e ininterrupto de experi\u00eancia profissional. Al\u00e9m disso, foram concedidos dois pontos extras aos residentes de uma das 28 comunidades listadas no edital.<\/p>\n<blockquote wp_automatic_readability=\"13\">\n<p>\u2013 A Comlurb ficou mais de 10 anos sem contratar garis, ent\u00e3o esse momento marca a retomada desse processo. Estamos substituindo os trabalhadores que atuavam em projetos de garis tempor\u00e1rios por profissionais aprovados em um processo seletivo p\u00fablico, que teve mais de 182 mil inscritos. Hoje, iniciamos o treinamento te\u00f3rico dos 400 primeiros contratados. Depois, eles passam por um treinamento t\u00e9cnico e s\u00e3o distribu\u00eddos nas ger\u00eancias. \u00c9 um marco importante para a Companhia. \u2013 afirmou o presidente da Comlurb, Jorge Arraes.<\/p>\n<\/blockquote>\n<p>A Comlurb convocou, em 16 de junho, os 600 primeiros colocados para apresenta\u00e7\u00e3o de documentos comprobat\u00f3rios. Desses, 400 foram selecionados e submetidos ao exame de sa\u00fade ocupacional, que atestou a aptid\u00e3o f\u00edsica para o exerc\u00edcio da fun\u00e7\u00e3o. A jornada de trabalho \u00e9 de 44 horas semanais, distribu\u00eddas de acordo com as necessidades operacionais da Companhia, incluindo s\u00e1bados e com possibilidade de escalas aos domingos e feriados. A remunera\u00e7\u00e3o mensal base \u00e9 de R$ 1.766,31, acrescida de adicional de insalubridade de at\u00e9 40%, vale-refei\u00e7\u00e3o no valor de R$ 26,21 por dia efetivamente trabalhado, al\u00e9m de aux\u00edlio transporte.<\/p>\n<blockquote wp_automatic_readability=\"10\">\n<p>\u2013 Estou feliz e lisonjeado de trabalhar na Comlurb servindo a comunidade onde nasci fui criado e ainda moro: a Fazenda Botafogo, na Pavuna. Estarei em casa \u2013 disse o gari Diego da Concei\u00e7\u00e3o, de 37 anos, um dos selecionados.<\/p>\n<\/blockquote>\n<p><strong>Sobre a Comlurb<\/strong><\/p>\n<p>A Comlurb comemorou, em maio, 50 anos de hist\u00f3ria. Desde os tempos da vassoura de palha e das carro\u00e7as at\u00e9 os dias atuais, a empresa evoluiu significativamente. Atualmente, \u00e9 a maior empresa de limpeza urbana da Am\u00e9rica Latina, com cerca de 13 mil garis respons\u00e1veis por v\u00e1rios servi\u00e7os, como coleta domiciliar e seletiva, varri\u00e7\u00e3o de ruas, limpeza de praias, pra\u00e7as, parques, hospitais e escolas municipais, al\u00e9m de poda de \u00e1rvores e higieniza\u00e7\u00e3o de encostas com o aux\u00edlio de garis alpinistas. Diariamente, a Companhia remove cerca de 9 mil toneladas de res\u00edduos.<\/p>\n<p>Desde 2022, a Comlurb vem modernizando sua opera\u00e7\u00e3o com a renova\u00e7\u00e3o da frota e aquisi\u00e7\u00e3o de novos equipamentos, como ro\u00e7adeiras port\u00e1teis, desbastadores (utilizados para o corte rente ao solo de tocos de \u00e1rvores removidas), tratores adaptados para atua\u00e7\u00e3o em comunidades, al\u00e9m de embarca\u00e7\u00f5es voltadas \u00e0 limpeza das ilhas da Barra da Tijuca, da Lagoa Rodrigo de Freitas e do entorno do Museu do Amanh\u00e3.<\/p>\n<p>Tamb\u00e9m foram incorporados vans e caminh\u00f5es para revitaliza\u00e7\u00e3o de pra\u00e7as e parques, bem como tratores de praia com implemento traseiro para peneiramento da areia, capazes de remover res\u00edduos menores. Ao todo, 62 novos ecopontos foram instalados em comunidades da cidade.<\/p>\n<p>             <!-- Compartilhe ---><\/p>\n<p>\t\t\t <!-- TAGS --><\/p>\n<section class=\"category-tags\">\n<div class=\"marcacao-category\">\n<article class=\"category-post\">\n<p>Categoria: <\/p>\n<\/article>\n<li>30 de junho de 2025<\/li><\/div>\n<article class=\"tags\">\n\t\t\t\t\tMarca\u00e7\u00f5es: Comlurb contrata\u00e7\u00e3o garis limpeza novos garis Prefeitura do Rio processo seletivo ruas<br \/><\/article>\n<\/section>\n<p>            <!-- Mais Not&iacute;cias --><\/p>\n<p>\t\t<!-- Conte&uacute;do SIDEBAR --><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Contratos t\u00eam prazo de um ano, podendo ser prorrogados at\u00e9 cinco vezes &#8211; F\u00e1bio Motta\/Prefeitura&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-25201","post","type-post","status-publish","format-standard","hentry","category-jogos-ao-vivo"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/25201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=25201"}],"version-history":[{"count":0,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/25201\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=25201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=25201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=25201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}