{"id":27134,"date":"2025-08-02T07:46:53","date_gmt":"2025-08-02T10:46:53","guid":{"rendered":"https:\/\/ipatingafc.com.br\/index.php\/2025\/08\/02\/moraes-compara-atos-de-eduardo-bolsonaro-nos-eua-a-tentativa-de-golpe\/"},"modified":"2025-08-02T07:46:53","modified_gmt":"2025-08-02T10:46:53","slug":"moraes-compara-atos-de-eduardo-bolsonaro-nos-eua-a-tentativa-de-golpe","status":"publish","type":"post","link":"https:\/\/ipatingafc.com.br\/index.php\/2025\/08\/02\/moraes-compara-atos-de-eduardo-bolsonaro-nos-eua-a-tentativa-de-golpe\/","title":{"rendered":"Moraes compara atos de Eduardo Bolsonaro nos EUA a tentativa de golpe"},"content":{"rendered":"<p><\/p>\n<div wp_automatic_readability=\"99.714849531327\">\n<p>O ministro do Supremo Tribunal Federal (STF) Alexandre de Moraes, comparou a atua\u00e7\u00e3o do deputado federal Eduardo Bolsonaro nos Estados Unidos \u00e0 tentativa de golpe de Estado do dia 8 de janeiro de 2023. Ele disparou contra a articula\u00e7\u00e3o do deputado junto \u00e0 Casa Branca para prejudic\u00e1-lo e conseguir anistia para o pai, o ex-presidente Jair Bolsonaro.<\/p>\n<p>\u201cO<em> modus operandi<\/em> golpista \u00e9 o mesmo. Antes acampamentos na frente dos quart\u00e9is, invas\u00e3o na Pra\u00e7a dos Tr\u00eas Poderes. Para que houvesse, como mais de 500 r\u00e9us confessaram, a convoca\u00e7\u00e3o de GLO [Garantia da Lei e da Ordem] e as For\u00e7as Armadas, gerando uma como\u00e7\u00e3o nacional e a possibilidade do golpe\u201d, disse o ministro nesta sexta-feira (1\u00ba), na sess\u00e3o de abertura do Supremo Tribunal Federal (STF) ap\u00f3s o recesso.<\/p>\n<p>\u201cO <em>modus operandi <\/em>\u00e9 o mesmo. Incentivo \u00e0 taxa\u00e7\u00e3o ao Brasil, incentivo \u00e0 crise econ\u00f4mica, que gera crise social, que gera crise pol\u00edtica. Para que novamente haja instabilidade social e a possibilidade de um novo ataque golpista\u201d, acrescentou.<\/p>\n<p><strong>STF retomar\u00e1 julgamento de Zambelli por porte ilegal de arma de fogo<\/strong><\/p>\n<p><strong>Tarifa\u00e7o imp\u00f5e desafios para ind\u00fastria qu\u00edmica nacional, diz Abiquim<\/strong><\/p>\n<p>A sess\u00e3o de abertura, na manh\u00e3 desta sexta-feira, foi marcada pela primeira manifesta\u00e7\u00e3o conjunta de ministros da Corte ap\u00f3s o governo do presidente dos Estados Unidos, Donald Trump, anunciar san\u00e7\u00f5es financeiras contra Moraes e formalizar a aplica\u00e7\u00e3o de tarifas de 50% a v\u00e1rios produtos que o Brasil comercializa com o pa\u00eds norte-americano.<\/p>\n<p>Assim que as tarifas contra o Brasil foram anunciadas por Trump, no in\u00edcio de julho, Eduardo Bolsonaro agradeceu ao presidente norte-americano. Em carta enviada ao governo brasileiro, na ocasi\u00e3o, Trump associou a aplica\u00e7\u00e3o de tarifas ao processo a que Jair Bolsonaro responde por tentativa de golpe de Estado.<\/p>\n<p>Al\u00e9m de Moraes, o presidente da Corte, Lu\u00eds Roberto Barroso, tamb\u00e9m discursou. Outros a se pronunciarem foram o\u00a0ministro Gilmar Mendes;\u00a0o Procurador-Geral da Rep\u00fablica, Paulo Gonet; e o advogado-geral da Uni\u00e3o, Jorge Messias.<\/p>\n<h2>\u201cMilicianos\u201d<\/h2>\n<p>Por diversas vezes, Moraes chamou de \u201ctraidores da p\u00e1tria\u201d aqueles que articulam medidas prejudiciais \u00e0 economia do Brasil junto ao governo dos Estados Unidos, mas n\u00e3o citou nominalmente Eduardo Bolsonaro ou outro aliado do ex-presidente. Tamb\u00e9m afirmou que a conduta vista atualmente \u00e9 comum a \u201cmilicianos do submundo do crime\u201d.<\/p>\n<p><strong>Haddad diz que governo tem disposi\u00e7\u00e3o em conversar com Trump<\/strong><\/p>\n<p><strong>Governo autorizar\u00e1 estados a comprar alimentos afetados por tarifa\u00e7o<\/strong><\/p>\n<p>\u201cEsses r\u00e9us, investigados, n\u00e3o est\u00e3o s\u00f3 amea\u00e7ando e coagindo autoridades p\u00fablicas, mas tamb\u00e9m \u2013 e fazem isso diariamente nas redes sociais \u2013 amea\u00e7ando as fam\u00edlias dos ministros do Supremo Tribunal Federal, do Procurador-Geral da Rep\u00fablica, em uma atitude costumeiramente afeita a milicianos do submundo do crime, que atacam as autoridades e os familiares das autoridades\u201d.<\/p>\n<p>De acordo com o ministro, a a\u00e7\u00e3o dessas pessoas junto ao governo de Donald Trump caracteriza \u201cclaros e expressos atos execut\u00f3rios de trai\u00e7\u00e3o ao Brasil e flagrantes confiss\u00f5es da pr\u00e1tica de atos criminosos\u201d. Em seguida, descreveu quais crimes elas estariam praticando: coa\u00e7\u00e3o no curso do processo, obstru\u00e7\u00e3o de investiga\u00e7\u00e3o de infra\u00e7\u00e3o penal que envolva organiza\u00e7\u00e3o criminosa e atentado \u00e0 soberania nacional.<\/p>\n<p>Sem citar nomes, o ministro tamb\u00e9m afirmou que a atua\u00e7\u00e3o de pessoas ligadas a Jair Bolsonaro busca um \u201ctir\u00e2nico arquivamento para beneficiar determinadas pessoas que se acham acima da Constitui\u00e7\u00e3o, da lei e das institui\u00e7\u00f5es\u201d.<\/p>\n<p>Em mar\u00e7o deste ano, Eduardo pediu licen\u00e7a do mandato parlamentar e foi morar nos Estados Unidos, sob a alega\u00e7\u00e3o de persegui\u00e7\u00e3o pol\u00edtica. A licen\u00e7a terminou no \u00faltimo dia 20.<\/p>\n<p>Apesar da grande repercuss\u00e3o, a aplica\u00e7\u00e3o de san\u00e7\u00f5es financeiras contra Alexandre de Moraes\u00a0n\u00e3o deve ter o impacto esperado pelo governo Trump\u00a0e aliados do ex-presidente Jair Bolsonaro.<\/p>\n<p>\u00a0<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O ministro do Supremo Tribunal Federal (STF) Alexandre de Moraes, comparou a atua\u00e7\u00e3o do deputado&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-27134","post","type-post","status-publish","format-standard","hentry","category-jogos-ao-vivo"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=27134"}],"version-history":[{"count":0,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27134\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=27134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=27134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=27134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}