{"id":31261,"date":"2025-10-10T04:27:15","date_gmt":"2025-10-10T07:27:15","guid":{"rendered":"https:\/\/ipatingafc.com.br\/index.php\/2025\/10\/10\/justica-condena-sp-a-multa-de-r-248-mi-por-nao-ofertar-aborto-legal\/"},"modified":"2025-10-10T04:27:15","modified_gmt":"2025-10-10T07:27:15","slug":"justica-condena-sp-a-multa-de-r-248-mi-por-nao-ofertar-aborto-legal","status":"publish","type":"post","link":"https:\/\/ipatingafc.com.br\/index.php\/2025\/10\/10\/justica-condena-sp-a-multa-de-r-248-mi-por-nao-ofertar-aborto-legal\/","title":{"rendered":"Justi\u00e7a condena SP a multa de R$ 24,8 mi por n\u00e3o ofertar aborto legal"},"content":{"rendered":"<p><\/p>\n<div wp_automatic_readability=\"47.938041002278\">\n<p><strong>A Justi\u00e7a, em decis\u00e3o liminar, condenou a prefeitura de S\u00e3o Paulo a pagar multa no valor\u00a0de R$ 24,8 milh\u00f5es\u00a0por n\u00e3o apresentar alternativas ao servi\u00e7o de atendimento de aborto legal <\/strong>em gesta\u00e7\u00f5es acima de 22 semanas no munic\u00edpio. O servi\u00e7o\u00a0era realizado pelo\u00a0Hospital Vila Nova Cachoeirinha, mas foi encerrado.<\/p>\n<p><strong>A magistrada Simone Casoretti considerou que o munic\u00edpio deixou de garantir o atendimento e oferecer alternativas a v\u00edtimas de estupro pelo per\u00edodo de 497 dias<\/strong>, entre 22\/01\/2024 e 02\/06\/2025. A ju\u00edza ainda cita\u00a015 casos de mulheres n\u00e3o atendidas, apresentados pela Defensoria P\u00fablica, e a falta de encaminhamento\u00a0para outras unidades de sa\u00fade.\u00a0<\/p>\n<p>Para a ju\u00edza, houve \u201cdesobedi\u00eancia institucional reiterada com n\u00edtido desprezo pelos direitos fundamentais como a sa\u00fade e a dignidade das mulheres v\u00edtimas de viol\u00eancia sexual\u201d.<\/p>\n<p><strong>Moraes destitui advogados de dois r\u00e9us do N\u00facleo 2 da trama golpista<\/strong><\/p>\n<p><strong>Justi\u00e7a suspende prorroga\u00e7\u00e3o antecipada da concess\u00e3o da Enel em SP<\/strong><\/p>\n<p>\u201cO valor da multa di\u00e1ria \u00e9 compat\u00edvel com a gravidade da situa\u00e7\u00e3o, tem como finalidade garantir a efetividade da jurisdi\u00e7\u00e3o e a prote\u00e7\u00e3o dos direitos fundamentais\u201d, diz a magistrada, na decis\u00e3o.\u00a0<\/p>\n<p>O valor da multa tem como destino o Fundo Estadual dos Direitos da Crian\u00e7a e do Adolescente (FEDCA), que ser\u00e1 usado em projetos espec\u00edficos voltados a crian\u00e7as e adolescentes v\u00edtimas de estupro e a garantia do acesso ao aborto legal.<\/p>\n<p>Em nota encaminhada \u00e0 <strong>TV Brasil<\/strong>, a <strong>prefeitura afirmou ir\u00e1 recorrer da decis\u00e3o<\/strong> assim que for intimada e\u00a0\u201centende que as decis\u00f5es t\u00e9cnicas feitas por m\u00e9dicos e profissionais da sa\u00fade devem prevalecer sobre quest\u00f5es ideol\u00f3gicas\u201d.\u00a0\u201cA Secretaria Municipal da Sa\u00fade reitera que o atendimento para aborto legal \u00e9 realizado na cidade em quatro hospitais municipais: C\u00e1rmino Caricchio (Tatuap\u00e9), Fernando Mauro Pires da Rocha (Campo Limpo), Tide Set\u00fabal (S\u00e3o Miguel Paulista) e M\u00e1rio Degni (Jardim Sarah)\u201d.<\/p>\n<p><em>* Com informa\u00e7\u00f5es da TV Brasil<\/em><\/p>\n<p><strong>S\u00e3o Paulo confirma tr\u00eas\u00a0novos casos de intoxica\u00e7\u00e3o por metanol<\/strong><\/p>\n<p><strong>Flotilha: brasileiros relatam torturas causadas por for\u00e7as israelenses<\/strong><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Justi\u00e7a, em decis\u00e3o liminar, condenou a prefeitura de S\u00e3o Paulo a pagar multa no&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-31261","post","type-post","status-publish","format-standard","hentry","category-jogos-ao-vivo"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=31261"}],"version-history":[{"count":0,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31261\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=31261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=31261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=31261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}