{"id":37375,"date":"2026-02-03T03:03:27","date_gmt":"2026-02-03T06:03:27","guid":{"rendered":"https:\/\/ipatingafc.com.br\/index.php\/2026\/02\/03\/agencia-minas-gerais-governador-destaca-adesao-ao-propag-e-avancos-na-saude-e-educacao-na-abertura-do-ano-legislativo-da-almg-2\/"},"modified":"2026-02-03T03:03:27","modified_gmt":"2026-02-03T06:03:27","slug":"agencia-minas-gerais-governador-destaca-adesao-ao-propag-e-avancos-na-saude-e-educacao-na-abertura-do-ano-legislativo-da-almg-2","status":"publish","type":"post","link":"https:\/\/ipatingafc.com.br\/index.php\/2026\/02\/03\/agencia-minas-gerais-governador-destaca-adesao-ao-propag-e-avancos-na-saude-e-educacao-na-abertura-do-ano-legislativo-da-almg-2\/","title":{"rendered":"Ag\u00eancia Minas Gerais | Governador destaca ades\u00e3o ao Propag e avan\u00e7os na sa\u00fade e educa\u00e7\u00e3o na abertura do ano legislativo da ALMG"},"content":{"rendered":"<p><\/p>\n<div>\n<section class=\"news-related \/ col-md-4 col-lg-3 \/ margin-md-bottom-2 margin-left-1 \/ pull-right \/ hidden-xs hidden-sm\">\n<header>\n<p class=\"text-title-section \/ margin-bottom-1\">Relacionadas<\/p>\n<\/header>\n<p>\t\t\t\t\t\t\t<main><\/p>\n<hr class=\"row margin-md-bottom-2\"\/>\n\t\t\t\t\t\t\t<\/main><br \/>\n\t\t\t\t\t\t<\/section>\n<p>O governador Romeu Zema participou, nesta segunda-feira (2\/2), da solenidade de instala\u00e7\u00e3o da 4\u00aa Sess\u00e3o Legislativa Ordin\u00e1ria da 20\u00aa Legislatura, que marca a retomada dos trabalhos dos deputados da Assembleia Legislativa de Minas Gerais (ALMG).<\/p>\n<p>Durante a reuni\u00e3o, conduzida pelo presidente da Casa, deputado Tadeu Martins Leite, o chefe do Executivo mineiro leu a mensagem governamental, onde fez um balan\u00e7o da gest\u00e3o do Governo do Estado e ressaltou a parceria com o Legislativo estadual na condu\u00e7\u00e3o de diversas a\u00e7\u00f5es voltadas \u00e0 popula\u00e7\u00e3o mineira.<\/p>\n<p>\u201cHoje, posso dizer que a Assembleia Legislativa tamb\u00e9m foi fundamental para viabilizar a solu\u00e7\u00e3o para a d\u00edvida de Minas Gerais com a Uni\u00e3o. O Propag vai tornar Minas um estado financeiramente vi\u00e1vel e, com isso, os mineiros podem esperar ainda mais acesso \u00e0 sa\u00fade, educa\u00e7\u00e3o, seguran\u00e7a, emprego e infraestrutura\u201d, enfatizou Romeu Zema.<\/p>\n<p>A formaliza\u00e7\u00e3o da ades\u00e3o ao Programa de Pleno Pagamento de D\u00edvidas dos Estados (Propag) ocorreu em dezembro do ano passado e a primeira parcela foi quitada em janeiro.<\/p>\n<p>\u201cFoi uma decis\u00e3o dif\u00edcil, que exigiu di\u00e1logo, escuta e compromisso com o futuro. Uma decis\u00e3o que reafirmou o papel desta Casa como um espa\u00e7o central de debates qualificados e de solu\u00e7\u00f5es poss\u00edveis para os grandes desafios do nosso tempo\u201d, acrescentou Tadeu Leite.<\/p>\n<p>Ainda entre os projetos que contaram com aprecia\u00e7\u00e3o da Casa, Zema falou sobre desestatiza\u00e7\u00e3o da Copasa. \u201cA companhia de saneamento do nosso estado vai passar por uma revolu\u00e7\u00e3o com o objetivo de levar \u00e1gua pot\u00e1vel e saneamento b\u00e1sico a todas as regi\u00f5es de Minas, um estado gigante, com desafios enormes\u201d, afirmou.<\/p>\n<p><strong>Sa\u00fade e educa\u00e7\u00e3o<\/strong><\/p>\n<p>O governador ressaltou a retomada de obras paradas de Unidades B\u00e1sicas de Sa\u00fade (UBS) e dos hospitais regionais. \u201cVi, ao longo dos anos, praticamente todos os senhores deputados concordarem que esta \u00e9 uma medida fundamental para levar a sa\u00fade para mais perto dos mineiros. J\u00e1 entregamos a obra do Hospital Regional de Te\u00f3filo Otoni e, at\u00e9 o fim do ano, entregaremos mais quatro hospitais em Divin\u00f3polis, Sete Lagoas, Governador Valadares e Conselheiro Lafaiete\u201d, disse Romeu Zema.<\/p>\n<p>Ele tamb\u00e9m enfatizou os avan\u00e7os\u00a0na \u00e1rea da educa\u00e7\u00e3o, como Minas Bil\u00edngue, projeto que vai levar o conte\u00fado tradicional em um segundo idioma a 30 escolas estaduais j\u00e1 no in\u00edcio deste ano letivo.<\/p>\n<p>\u201cTivemos o maior avan\u00e7o do pa\u00eds na alfabetiza\u00e7\u00e3o de crian\u00e7as. Chegamos a 72% dos estudantes alfabetizados \u2014 superando a meta nacional. O Trilhas de Futuro fez Minas se tornar l\u00edder na cria\u00e7\u00e3o de vagas para a educa\u00e7\u00e3o t\u00e9cnica, com o dobro de vagas em rela\u00e7\u00e3o ao 2\u00ba colocado, o Estado de S\u00e3o Paulo. Isso significa mais jovens preparados para o mercado de trabalho\u201d, ressaltou.<\/p>\n<p>O governador tamb\u00e9m abordou a retomada do crescimento de Minas Gerais, com a atra\u00e7\u00e3o de mais de meio trilh\u00e3o de reais em investimentos e a marca de 1 milh\u00e3o de novos empregos com carteira assinada entre 2019 e 2025.<\/p>\n<p>\u201cAinda temos muito a fazer. Este ano de 2026 ser\u00e1 decisivo para Minas e para o Brasil, e tenho esperan\u00e7a de que os mineiros v\u00e3o continuar no caminho da prosperidade\u201d, concluiu o governador.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Relacionadas O governador Romeu Zema participou, nesta segunda-feira (2\/2), da solenidade de instala\u00e7\u00e3o da 4\u00aa&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-37375","post","type-post","status-publish","format-standard","hentry","category-jogos-ao-vivo"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=37375"}],"version-history":[{"count":0,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37375\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=37375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=37375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=37375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}