{"id":37383,"date":"2026-02-03T06:10:37","date_gmt":"2026-02-03T09:10:37","guid":{"rendered":"https:\/\/ipatingafc.com.br\/index.php\/2026\/02\/03\/agencia-minas-gerais-secretaria-de-justica-e-seguranca-publica-firma-termo-para-ampliar-trabalho-prisional-e-ressocializacao-em-minas-3\/"},"modified":"2026-02-03T06:10:37","modified_gmt":"2026-02-03T09:10:37","slug":"agencia-minas-gerais-secretaria-de-justica-e-seguranca-publica-firma-termo-para-ampliar-trabalho-prisional-e-ressocializacao-em-minas-3","status":"publish","type":"post","link":"https:\/\/ipatingafc.com.br\/index.php\/2026\/02\/03\/agencia-minas-gerais-secretaria-de-justica-e-seguranca-publica-firma-termo-para-ampliar-trabalho-prisional-e-ressocializacao-em-minas-3\/","title":{"rendered":"Ag\u00eancia Minas Gerais | Secretaria de Justi\u00e7a e Seguran\u00e7a P\u00fablica firma termo para ampliar trabalho prisional e ressocializa\u00e7\u00e3o em Minas"},"content":{"rendered":"<p><\/p>\n<div>\n<section class=\"news-related \/ col-md-4 col-lg-3 \/ margin-md-bottom-2 margin-left-1 \/ pull-right \/ hidden-xs hidden-sm\">\n<header>\n<p class=\"text-title-section \/ margin-bottom-1\">Relacionadas<\/p>\n<\/header>\n<p>\t\t\t\t\t\t\t<main><\/p>\n<hr class=\"row margin-md-bottom-2\"\/>\n<hr class=\"row margin-md-bottom-2\"\/>\n<hr class=\"row margin-md-bottom-2\"\/>\n\t\t\t\t\t\t\t<\/main><br \/>\n\t\t\t\t\t\t<\/section>\n<p>A Secretaria de Estado de Justi\u00e7a e Seguran\u00e7a P\u00fablica de Minas Gerais (Sejusp) firmou, nesta segunda-feira (2\/2), no Pres\u00eddio Ant\u00f4nio Dutra Ladeira, em Ribeir\u00e3o das Neves, na Regi\u00e3o Metropolitana de Belo Horizonte (RMBH), o\u00a0Termo de Compromisso\u00a0com o\u00a0Minist\u00e9rio P\u00fablico de Minas Gerais (MPMG), o Servi\u00e7o Social Aut\u00f4nomo (Servas) e a Direcional Engenharia S\/A, marcando o in\u00edcio da execu\u00e7\u00e3o de um projeto que viabiliza a\u00e7\u00f5es de profissionaliza\u00e7\u00e3o, capacita\u00e7\u00e3o e ressocializa\u00e7\u00e3o de indiv\u00edduos privados de liberdade.<\/p>\n<p>O acordo prev\u00ea a implanta\u00e7\u00e3o progressiva de uma central de formas de alum\u00ednio para presta\u00e7\u00e3o de servi\u00e7os de pr\u00e9-montagem (mock up), manuten\u00e7\u00e3o e limpeza das formas utilizadas nos canteiros de obra da Direcional Engenharia S\/A, empresa que ir\u00e1 patrocinar e executar o projeto piloto, com possibilidade de expans\u00e3o.<\/p>\n<p>&#8220;A iniciativa fortalece a pol\u00edtica de trabalho prisional ao unir qualifica\u00e7\u00e3o profissional, responsabilidade social e gera\u00e7\u00e3o de oportunidades reais de ressocializa\u00e7\u00e3o, contribuindo para a redu\u00e7\u00e3o da reincid\u00eancia criminal e para a constru\u00e7\u00e3o de uma sociedade mais segura&#8221;, destacou o secret\u00e1rio de Estado de Justi\u00e7a e Seguran\u00e7a P\u00fablica, Rog\u00e9rio Greco.<\/p>\n<p>Os custodiados participantes receber\u00e3o remunera\u00e7\u00e3o correspondente a tr\u00eas quartos do sal\u00e1rio m\u00ednimo, conforme legisla\u00e7\u00e3o vigente, com divis\u00e3o entre ressarcimento ao Estado, repasse direto ao preso e dep\u00f3sito em conta pec\u00falio, al\u00e9m de contribui\u00e7\u00e3o previdenci\u00e1ria. Al\u00e9m das atividades laborais, a empresa realizar\u00e1 benfeitorias na unidade piloto, como a revitaliza\u00e7\u00e3o da portaria do complexo prisional e a reforma de celas.<\/p>\n<p>&#8220;N\u00f3s n\u00e3o estamos mudando uma realidade secular de forma imediata, mas estamos, sim, avan\u00e7ando em passos muito importantes, com a\u00e7\u00f5es concretas que trar\u00e3o benef\u00edcios reais para a sociedade. Isso \u00e9 motivo de muita alegria e d\u00e1 ainda mais sentido ao nosso trabalho&#8221;,\u00a0ressaltou o promotor de Justi\u00e7a, Carlos Eduardo Ferreira Pinto.<\/p>\n<p>Na primeira fase, o investimento previsto \u00e9 de R$ 1.345.280,20, com custo operacional mensal de R$ 82.670,95, envolvendo 22 presos. A segunda fase contar\u00e1 com investimento de R$ 394.961,63, opera\u00e7\u00e3o mensal de R$ 41.256,35 e participa\u00e7\u00e3o de dez detentos. &#8220;Acreditamos que a ressocializa\u00e7\u00e3o passa, principalmente, pela oportunidade de trabalho e qualifica\u00e7\u00e3o profissional. Ao oferecer emprego, damos a essas pessoas a chance real de reconstruir suas trajet\u00f3rias e retornar \u00e0 sociedade de forma digna&#8221;, afirmou o CEO da Direcional Engenharia S\/A, Ricardo Ribeiro Valadares Gontijo.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Relacionadas A Secretaria de Estado de Justi\u00e7a e Seguran\u00e7a P\u00fablica de Minas Gerais (Sejusp) firmou,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-37383","post","type-post","status-publish","format-standard","hentry","category-jogos-ao-vivo"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=37383"}],"version-history":[{"count":0,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37383\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=37383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=37383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=37383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}