{"id":39403,"date":"2026-03-09T21:12:58","date_gmt":"2026-03-10T00:12:58","guid":{"rendered":"https:\/\/ipatingafc.com.br\/index.php\/2026\/03\/09\/agencia-minas-gerais-governo-de-minas-inaugura-centro-de-imagem-de-hospital-em-vespasiano\/"},"modified":"2026-03-09T21:12:58","modified_gmt":"2026-03-10T00:12:58","slug":"agencia-minas-gerais-governo-de-minas-inaugura-centro-de-imagem-de-hospital-em-vespasiano","status":"publish","type":"post","link":"https:\/\/ipatingafc.com.br\/index.php\/2026\/03\/09\/agencia-minas-gerais-governo-de-minas-inaugura-centro-de-imagem-de-hospital-em-vespasiano\/","title":{"rendered":"Ag\u00eancia Minas Gerais | Governo de Minas inaugura centro de imagem de hospital em Vespasiano"},"content":{"rendered":"<p><\/p>\n<div>\n<section class=\"news-related \/ col-md-4 col-lg-3 \/ margin-md-bottom-2 margin-left-1 \/ pull-right \/ hidden-xs hidden-sm\">\n<header>\n<p class=\"text-title-section \/ margin-bottom-1\">Relacionadas<\/p>\n<\/header>\n<p>\t\t\t\t\t\t\t<main><\/p>\n<hr class=\"row margin-md-bottom-2\"\/>\n\t\t\t\t\t\t\t<\/main><br \/>\n\t\t\t\t\t\t<\/section>\n<p>O vice-governador Mateus Sim\u00f5es participou, nesta segunda-feira (9\/3), da solenidade de inaugura\u00e7\u00e3o do centro de imagem do Hospital de Deus, em Vespasiano, na Regi\u00e3o Metropolitana de Belo Horizonte (RMBH). Na ocasi\u00e3o, foi formalizada a entrega de um tom\u00f3grafo, um aparelho de raio-x e um equipamento de ultrassom, adquiridos com recursos repassados pelo Governo de Minas, por meio da Secretaria de Estado de Sa\u00fade de Minas Gerais (SES-MG), em 2025.<\/p>\n<p>&#8220;Fazer investimentos em sa\u00fade \u00e9 sempre motivo de comemora\u00e7\u00e3o. E, com a entrega de hoje, aqui em Vespasiano, o Governo de Minas chega \u00e0\u00a0instala\u00e7\u00e3o de mais de 100 tom\u00f3grafos e mais de 80 mam\u00f3grafos digitais\u00a0em todo o estado, uma revolu\u00e7\u00e3o completa da nossa condi\u00e7\u00e3o de realiza\u00e7\u00e3o de exames de alta complexidade em imagem para atendimento dos nossos pacientes&#8221;, disse Mateus Sim\u00f5es.<\/p>\n<p>Os equipamentos somam cerca de R$ 3,1 milh\u00f5es e v\u00e3o qualificar o atendimento de urg\u00eancia e emerg\u00eancia da popula\u00e7\u00e3o do munic\u00edpio. A cerim\u00f4nia de entrega dos aparelhos marcou a inaugura\u00e7\u00e3o do Servi\u00e7o de Apoio Diagn\u00f3stico Terap\u00eautico (SADT), que pode beneficiar 279 mil pessoas da microrregi\u00e3o de sa\u00fade de Vespasiano.<\/p>\n<p>Avaliado em R$ 2,57 milh\u00f5es, o tom\u00f3grafo pode realizar at\u00e9 1.120 exames por m\u00eas e vai beneficiar os pacientes oncol\u00f3gicos, cardiol\u00f3gicos e renais atendidos na institui\u00e7\u00e3o. O equipamento de ultrassom foi adquirido por cerca de R$ 177 mil e tem capacidade para 600 exames por m\u00eas. J\u00e1 o aparelho de raio-x, no valor de R$ 358,5 mil, pode realizar mais de mil exames por m\u00eas.<\/p>\n<p>Desde 2021, o Hospital de Deus foi contemplado com o repasse de cerca de R$ 5,6 milh\u00f5es referente \u00e0 pol\u00edtica Valora Minas, que qualifica a aten\u00e7\u00e3o hospitalar e o acesso aos servi\u00e7os de sa\u00fade. A institui\u00e7\u00e3o tamb\u00e9m recebeu, no mesmo per\u00edodo, aproximadamente R$ 4,9 milh\u00f5es referente \u00e0 pol\u00edtica &#8220;Opera Mais, Minas Gerais&#8221;, que visa ampliar o acesso a cirurgias eletivas e reduzir as filas de espera para os procedimentos cir\u00fargicos. Desde a implementa\u00e7\u00e3o, foram realizadas mais de 5 mil cirurgias eletivas em Vespasiano.<\/p>\n<p><strong>Interven\u00e7\u00f5es<\/strong><\/p>\n<p>As obras de reforma e amplia\u00e7\u00e3o na unidade v\u00e3o contribuir para que os atendimentos sejam realizados no pr\u00f3prio munic\u00edpio, reduzindo as transfer\u00eancias para outras localidades e levando o servi\u00e7o de sa\u00fade de qualidade para perto da popula\u00e7\u00e3o. Com a obra, a institui\u00e7\u00e3o vai contar com mais de 7 mil metros quadrados de \u00e1rea constru\u00edda.<\/p>\n<p>O investimento na reforma e amplia\u00e7\u00e3o do hospital corresponde a um total de R$ 70 milh\u00f5es. Nesta fase inicial, o Governo de Minas investiu R$ 20 milh\u00f5es em equipamentos e o valor restante, de R$ 50 milh\u00f5es, ser\u00e1 investido na etapa seguinte, destinada \u00e0s amplia\u00e7\u00f5es da infraestrutura.<\/p>\n<p>Ap\u00f3s a obra, a unidade passar\u00e1 a contar com instala\u00e7\u00f5es para especialidades como cl\u00ednica m\u00e9dica e cir\u00fargica, trazendo mais benef\u00edcios para toda a regi\u00e3o. A previs\u00e3o de t\u00e9rmino de todas as etapas da obra \u00e9 de at\u00e9 dois anos.<\/p>\n<p><strong>Sa\u00fade em Vespasiano<\/strong><\/p>\n<p>A entrega do tom\u00f3grafo se soma a uma s\u00e9rie de investimentos e repasses estaduais para otimizar o atendimento em sa\u00fade \u00e0 popula\u00e7\u00e3o. Vespasiano recebeu mais de R$ 2 milh\u00f5es para a compra de ve\u00edculos do Transporta SUS, um vacim\u00f3vel no valor de R$ 409 mil e mais de R$ 100 mil para a operacionaliza\u00e7\u00e3o da Pol\u00edtica Vigidrones, que utiliza drones para o mapeamento de poss\u00edveis focos do Aedes aegypti.<\/p>\n<p>Al\u00e9m dos equipamentos entregues, mais R$ 119 milh\u00f5es foram repassados ao Fundo Municipal de Sa\u00fade desde 2019, sendo mais de R$ 33 milh\u00f5es no ano de 2025. Entre 2019 e 2025, foram destinados cerca de R$ 19 milh\u00f5es para Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade, incluindo R$ 4,3 milh\u00f5es para a constru\u00e7\u00e3o de duas Unidades B\u00e1sicas de Sa\u00fade (UBSs) do tipo II.<\/p>\n<p>O Governo de Minas Gerais ainda investiu cerca de R$ 4 milh\u00f5es para a aquisi\u00e7\u00e3o de equipamentos e implementa\u00e7\u00e3o de um novo centro de hemodi\u00e1lise que atender\u00e1 \u00e0 microrregi\u00e3o de Lagoa Santa\/Vespasiano, que atualmente tem como refer\u00eancia de os servi\u00e7os habilitados na microrregi\u00e3o BH\/Nova Lima\/Santa Luzia.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Relacionadas O vice-governador Mateus Sim\u00f5es participou, nesta segunda-feira (9\/3), da solenidade de inaugura\u00e7\u00e3o do centro&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-39403","post","type-post","status-publish","format-standard","hentry","category-jogos-ao-vivo"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=39403"}],"version-history":[{"count":0,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39403\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=39403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=39403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=39403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}