{"id":41356,"date":"2026-04-12T08:30:51","date_gmt":"2026-04-12T11:30:51","guid":{"rendered":"https:\/\/ipatingafc.com.br\/index.php\/2026\/04\/12\/projeto-garoto-cidadao-abre-vagas-para-o-periodo-matutino-em-bonito\/"},"modified":"2026-04-12T08:30:51","modified_gmt":"2026-04-12T11:30:51","slug":"projeto-garoto-cidadao-abre-vagas-para-o-periodo-matutino-em-bonito","status":"publish","type":"post","link":"https:\/\/ipatingafc.com.br\/index.php\/2026\/04\/12\/projeto-garoto-cidadao-abre-vagas-para-o-periodo-matutino-em-bonito\/","title":{"rendered":"Projeto Garoto Cidad\u00e3o abre vagas para o per\u00edodo matutino em Bonito"},"content":{"rendered":"<p><\/p>\n<div wp_automatic_readability=\"36.079417604236\">\n<p>Crian\u00e7as e adolescentes de Bonito t\u00eam uma nova oportunidade de participar de atividades socioculturais no contraturno escolar. Est\u00e3o abertas vagas para o per\u00edodo matutino do Projeto Garoto Cidad\u00e3o, iniciativa que promove desenvolvimento pessoal, inclus\u00e3o e acesso \u00e0 cultura.<\/p>\n<p>O programa \u00e9 realizado pela Funda\u00e7\u00e3o CSN, com apoio do Grupo Santa Ot\u00edlia, em parceria com a Prefeitura de Bonito.<\/p>\n<p>Voltado para o p\u00fablico de 9 a 17 anos, o projeto oferece atividades duas vezes por semana, contemplando diferentes linguagens, como Cultura e Cidadania, Dan\u00e7a, M\u00fasica e Teatro. Para participar, \u00e9 necess\u00e1rio estar matriculado na rede p\u00fablica de ensino (municipal ou estadual).<\/p>\n<p><strong>Fam\u00edlias do Tr\u00eas Cora\u00e7\u00f5es recebem atendimentos sem sair da comunidade \u2013 CGNot\u00edcias<\/strong><\/p>\n<p><strong>Coxim celebrou 128 anos com pacote de investimentos, obras e novos marcos para o futuro \u2013 Ag\u00eancia de Noticias do Governo de Mato Grosso do Sul<\/strong><\/p>\n<p>As matr\u00edculas s\u00e3o realizadas na sede do projeto, localizada na Rua P\u00e9rsio Schamann, n\u00ba 645, Centro, de segunda a sexta-feira, das 8h \u00e0s 10h30 e das 13h \u00e0s 16h30.<\/p>\n<p><strong>Documentos necess\u00e1rios para matr\u00edcula:<\/strong><\/p>\n<ul class=\"wp-block-list\">\n<li>Declara\u00e7\u00e3o de matr\u00edcula escolar atual;<\/li>\n<li>RG e CPF do respons\u00e1vel;<\/li>\n<li>Certid\u00e3o de nascimento ou RG e CPF da crian\u00e7a\/adolescente;<\/li>\n<li>Comprovante de resid\u00eancia atualizado;<\/li>\n<li>Laudo m\u00e9dico, atestado ou receita de uso cont\u00ednuo (caso haja acompanhamento m\u00e9dico ou psicol\u00f3gico).<\/li>\n<\/ul>\n<p>Mais informa\u00e7\u00f5es podem ser obtidas pelo telefone (67) 9 9244-7450.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Crian\u00e7as e adolescentes de Bonito t\u00eam uma nova oportunidade de participar de atividades socioculturais no&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-41356","post","type-post","status-publish","format-standard","hentry","category-jogos-ao-vivo"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=41356"}],"version-history":[{"count":0,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41356\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=41356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=41356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=41356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}