{"id":43210,"date":"2026-05-13T16:15:34","date_gmt":"2026-05-13T19:15:34","guid":{"rendered":"https:\/\/ipatingafc.com.br\/index.php\/2026\/05\/13\/brasil-fecha-2025-com-aumento-de-5-no-estoque-de-empregos\/"},"modified":"2026-05-13T16:15:34","modified_gmt":"2026-05-13T19:15:34","slug":"brasil-fecha-2025-com-aumento-de-5-no-estoque-de-empregos","status":"publish","type":"post","link":"https:\/\/ipatingafc.com.br\/index.php\/2026\/05\/13\/brasil-fecha-2025-com-aumento-de-5-no-estoque-de-empregos\/","title":{"rendered":"Brasil fecha 2025 com aumento de 5% no estoque de empregos"},"content":{"rendered":"<p><\/p>\n<div wp_automatic_readability=\"143.55607601713\">\n<p>O Brasil fechou o ano de 2025 com um aumento de 5% no estoque de empregos formais, na compara\u00e7\u00e3o com 2024. <strong>O pa\u00eds fechou o ano passado com 59,971 milh\u00f5es de trabalhadores com emprego formal.<\/strong>\u00a0<\/p>\n<p>Desse total, 46,128 milh\u00f5es s\u00e3o celetistas; 12,657 milh\u00f5es estatut\u00e1rios e trabalhadores em organiza\u00e7\u00f5es sem fins lucrativos, sindicatos, pessoa f\u00edsica rural, entre outros, somaram 1,186 milh\u00e3o.<\/p>\n<p>As informa\u00e7\u00f5es constam da Rela\u00e7\u00e3o Anual de Informa\u00e7\u00f5es Sociais (Rais) divulgada nesta quarta-feira (13) pelo Minist\u00e9rio do Trabalho e Emprego.\u00a0<\/p>\n<p><strong>Morte do padre Geraldo \u00e9 confirmada e causa como\u00e7\u00e3o<\/strong><\/p>\n<p><strong>LATAM prepara estreia do Embraer E2 no Brasil e primeiras rotas ser\u00e3o reveladas em junho<\/strong><\/p>\n<blockquote wp_automatic_readability=\"12\">\n<p>\u201cApresentamos recentemente o menor \u00edndice de desemprego da hist\u00f3ria. Estamos num momento bom, apesar dos juros altos. Estamos no rumo certo. Poder\u00edamos estar em uma situa\u00e7\u00e3o melhor se n\u00e3o fossem os juros praticados\u201d, disse o ministro do Trabalho e Emprego, Luiz Marinho, ao divulgar os n\u00fameros.<\/p>\n<\/blockquote>\n<p><strong>O principal setor respons\u00e1vel pelo estoque de empregos foi o de Servi\u00e7os, com 35,695 milh\u00f5es<\/strong>, uma alta de 7,2% em rela\u00e7\u00e3o a 2024. Na sequ\u00eancia, vem o Com\u00e9rcio, com crescimento de 1,7% e 10,487 milh\u00f5es de empregos, e a Ind\u00fastria com 9,017 milh\u00f5es e um crescimento tamb\u00e9m de 1,7%.<\/p>\n<p>&gt;&gt; Siga o canal da <strong>Ag\u00eancia Brasil <\/strong>no WhatsApp<\/p>\n<p>A constru\u00e7\u00e3o somou 2,57 milh\u00f5es de empregos, registrando uma alta de 2,5%, e a agropecu\u00e1ria, com 1,812 milh\u00f5es de empregos e um crescimento de 1,6%.<\/p>\n<p><strong>Sorteio comemorativo dos 30 anos da Mega-Sena ser\u00e1 em 24 de maio<\/strong><\/p>\n<p><strong>Durigan cancela viagem \u00e0 R\u00fassia ap\u00f3s fechamento de aeroporto<\/strong><\/p>\n<p><strong>No setor de servi\u00e7os, a administra\u00e7\u00e3o p\u00fablica mostrou crescimento de 15,2% no n\u00famero de empregos<\/strong>, com 1.483.555 v\u00ednculos. A maior parte desse crescimento ficou concentrada nos munic\u00edpios, com 18,2% (1,182 milh\u00f5es v\u00ednculos) e nos governos estaduais, de 10,3% (408.018 v\u00ednculos).<\/p>\n<p>Houve aumentos expressivos na educa\u00e7\u00e3o, com alta de 6,2% ou 212.611 v\u00ednculos, e de menor intensidade na sa\u00fade humana, com 4,2% ou 142.598 v\u00ednculos.<\/p>\n<p>Apesar do aumento no estoque de empregos, a Rais mostrou que houve uma ligeira queda na remunera\u00e7\u00e3o m\u00e9dia, de 0,5% na mesma base de compara\u00e7\u00e3o, chegando a R$ 4.434,38 em 2025.<\/p>\n<p><strong>A Rais \u00e9 divulgada anualmente e apresenta informa\u00e7\u00f5es sobre todos os estabelecimentos formais e v\u00ednculos celetistas e estatut\u00e1rios no Brasil.<\/strong> Segundo os dados, o n\u00famero de estabelecimentos com empregados passou de 4,7 milh\u00f5es para 4,8 milh\u00f5es, um crescimento de 2,1%.\u00a0<\/p>\n<p>Os n\u00fameros mostram ainda que entre as regi\u00f5es, o crescimento relativo foi mais intenso nas regi\u00f5es Nordeste, de 10,1%, com 1.076.603 v\u00ednculos criados; depois vem a Norte com crescimento de 10,1% e 354.753 v\u00ednculos; a Centro-Oeste, com alta de 5,7% e 322.513 v\u00ednculos.<\/p>\n<p><strong>A Regi\u00e3o Sudeste, com o crescimento de 2,9% e 807.240 v\u00ednculos, e a Sul, com alta de 2,9% e 285.514 v\u00ednculos, tamb\u00e9m tiveram aumentos absolutos expressivos.<\/strong>\u00a0<\/p>\n<p>A distribui\u00e7\u00e3o do emprego formal permaneceu concentrada na Regi\u00e3o Sudeste (47,4%), seguida pela Regi\u00e3o Nordeste (19,5%) e pela Regi\u00e3o Sul (16,8%).<\/p>\n<p><strong>Entre as Unidades da Federa\u00e7\u00e3o, o maior crescimento relativo do estoque de empregos em compara\u00e7\u00e3o a 2024 foi registrado no Amap\u00e1<\/strong>, com um crescimento de 20,5% e 31.396 v\u00ednculos; no Piau\u00ed, com alta de 13,2% e 74.244 v\u00ednculos; em Alagoas, cujo crescimento foi de 13%, gerando 81.633 v\u00ednculos; e na Para\u00edba, com 12,9% e 103.278 v\u00ednculos.<\/p>\n<p>Em varia\u00e7\u00e3o absoluta, os maiores crescimentos foram em S\u00e3o Paulo de 2,3% (357.493 v\u00ednculos), na Bahia, com 9,7% (266.035 v\u00ednculos), em Minas Gerais, crescimento de 3,7% (224.876) e no Cear\u00e1, com aumento de 10,6% (195.462 v\u00ednculos).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Brasil fechou o ano de 2025 com um aumento de 5% no estoque de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-43210","post","type-post","status-publish","format-standard","hentry","category-jogos-ao-vivo"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=43210"}],"version-history":[{"count":0,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43210\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=43210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=43210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=43210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}