{"id":45965,"date":"2026-06-29T10:55:15","date_gmt":"2026-06-29T13:55:15","guid":{"rendered":"https:\/\/ipatingafc.com.br\/index.php\/2026\/06\/29\/numero-de-mortos-em-terremotos-na-venezuela-se-aproxima-de-1-500\/"},"modified":"2026-06-29T10:55:15","modified_gmt":"2026-06-29T13:55:15","slug":"numero-de-mortos-em-terremotos-na-venezuela-se-aproxima-de-1-500","status":"publish","type":"post","link":"https:\/\/ipatingafc.com.br\/index.php\/2026\/06\/29\/numero-de-mortos-em-terremotos-na-venezuela-se-aproxima-de-1-500\/","title":{"rendered":"N\u00famero de mortos em terremotos na Venezuela se aproxima de 1.500"},"content":{"rendered":"<p><\/p>\n<div>\n<p>Equipes de resgate continuam a buscar\u00a0sobreviventes dos dois fortes terremotos que atingiram a Venezuela na semana passada, trazendo\u00a0pequeno al\u00edvio a uma busca sombria para reduzir a lista de dezenas de milhares de desaparecidos.<\/p>\n<p><strong>O n\u00famero de mortos nos dois terremotos ocorridos na quarta-feira se aproxima\u00a0de 1.500 pessoas, enquanto equipes de resgate estrangeiras chegam\u00a0em grande n\u00famero a La Guaira, o estado mais atingido de um pa\u00eds h\u00e1 muito atolado em profunda crise pol\u00edtica e econ\u00f4mica.<\/strong><\/p>\n<p>Dezenas de pr\u00e9dios desabaram, transformando-se em pilhas de areia e escombros no estado litor\u00e2neo, a cerca de 40 quil\u00f4metros\u00a0ao norte de Caracas.<\/p>\n<p><strong>Sistemas agroecol\u00f3gicos de quatro biomas s\u00e3o criados em Bras\u00edlia<\/strong><\/p>\n<p><strong>Governo abre cr\u00e9dito de R$ 550 milh\u00f5es para subsidiar diesel<\/strong><\/p>\n<blockquote>\n<p>\u201cOs esfor\u00e7os de resgate e recupera\u00e7\u00e3o continuam. Nesse domingo (28)\u00a0resgatamos pessoas com vida e, portanto, as opera\u00e7\u00f5es n\u00e3o ser\u00e3o suspensas. Sempre mantemos a esperan\u00e7a\u201d, disse a presidente interina Delcy Rodr\u00edguez, ap\u00f3s anunciar uma comiss\u00e3o presidencial que determinar\u00e1 as condi\u00e7\u00f5es\u00a0dos edif\u00edcios.<\/p>\n<\/blockquote>\n<p><strong>Ladeada por v\u00e1rios de seus ministros, ela afirmou que as aulas ser\u00e3o\u00a0suspensas por mais uma semana e que o fornecimento de eletricidade em La Guaira j\u00e1 foi restaurado em 75%.<\/strong><\/p>\n<p>O governo \u2014 liderado por Delcy Rodr\u00edguez desde que seu antecessor foi deposto pelos Estados Unidos (EUA)\u00a0em uma opera\u00e7\u00e3o militar em janeiro \u2014 agradeceu aos volunt\u00e1rios civis que transportam\u00a0ajuda para La Guaira, mas depois restringiu o acesso \u00e0 estrada, alegando que o tr\u00e1fego estava impedindo\u00a0a circula\u00e7\u00e3o eficiente dos ve\u00edculos de emerg\u00eancia.<\/p>\n<p><strong>Mais cedo, Jorge Rodr\u00edguez, irm\u00e3o da presidente interina e presidente da Assembleia Nacional, afirmou que o n\u00famero de mortos aumentou em 20 pessoas no domingo, chegando a 1.450. Ele acrescentou que 3.150 pessoas continuam\u00a0feridas, 12.721 foram deslocadas e 774 edif\u00edcios\u00a0desabaram<\/strong><\/p>\n<p><strong>Sala VIP Pedra Preta do Ita\u00fa come\u00e7a a operar em Guarulhos; veja quem pode acessar e as regras para convidados<\/strong><\/p>\n<p><strong>Brasil e Jap\u00e3o se enfrentam hoje no mata-mata; veja jogos da Copa<\/strong><\/p>\n<blockquote>\n<p>\u201cEstamos em momentos cr\u00edticos, em momentos cruciais para continuar resgatando vidas e construir acampamentos onde possam ficar as pessoas que perderam suas casas ou que, por qualquer motivo, n\u00e3o possam retornar \u00e0s suas resid\u00eancias\u201d, disse ele.<\/p>\n<\/blockquote>\n<p><strong>Fam\u00edlias e volunt\u00e1rios passaram dias retirando sobreviventes e corpos dos escombros antes da chegada dos mais de 2.600 socorristas estrangeiros, frequentemente reclamando da escassez de equipamentos pesados e da presen\u00e7a oficial limitada, enquanto centenas de r\u00e9plicas agravavam os danos e mantinham os moradores em estado de alerta.<\/strong><\/p>\n<p>Um pai e seu filho foram resgatados com vida dos escombros de um pr\u00e9dio que desabou\u00a0no domingo, enquanto equipes de resgate correm\u00a0contra o rel\u00f3gio para encontrar mais sobreviventes.<\/p>\n<p>Embora o governo tenha divulgado um n\u00famero de centenas de desaparecidos ou presos nos escombros, pouco menos de 50 mil pessoas est\u00e3o\u00a0listadas como desaparecidas em um<em> site<\/em>\u00a0produzido pela\u00a0oposi\u00e7\u00e3o\u00a0do pa\u00eds no domingo, uma ligeira queda em rela\u00e7\u00e3o \u00e0s 55 mil pessoas registradas no dia anterior.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Equipes de resgate continuam a buscar\u00a0sobreviventes dos dois fortes terremotos que atingiram a Venezuela na&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-45965","post","type-post","status-publish","format-standard","hentry","category-jogos-ao-vivo"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=45965"}],"version-history":[{"count":0,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/45965\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=45965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=45965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=45965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}