{"id":46098,"date":"2026-07-01T21:44:15","date_gmt":"2026-07-02T00:44:15","guid":{"rendered":"https:\/\/ipatingafc.com.br\/index.php\/2026\/07\/01\/belgica-vira-contra-o-senegal-com-penalti-no-final-da-prorrogacao\/"},"modified":"2026-07-01T21:44:15","modified_gmt":"2026-07-02T00:44:15","slug":"belgica-vira-contra-o-senegal-com-penalti-no-final-da-prorrogacao","status":"publish","type":"post","link":"https:\/\/ipatingafc.com.br\/index.php\/2026\/07\/01\/belgica-vira-contra-o-senegal-com-penalti-no-final-da-prorrogacao\/","title":{"rendered":"B\u00e9lgica vira contra o Senegal com p\u00eanalti no final da prorroga\u00e7\u00e3o"},"content":{"rendered":"<p><\/p>\n<div>\n<p><strong>Pela segunda fase da Copa do Mundo, a B\u00e9lgica \u2013 primeiro lugar no Grupo G \u2013 enfrentou Senegal \u2013 terceiro colocado no Grupo I \u2013 no est\u00e1dio de Seattle, nos Estados Unidos, nesta quarta-feira (2),\u00a0e sofreu para conseguir a vit\u00f3ria de virada por 3 a 2, que s\u00f3 saiu nos acr\u00e9scimos do segundo tempo da prorroga\u00e7\u00e3o, gra\u00e7as a um p\u00eanalti assinalado pelo \u00e1rbitro de v\u00eddeo.<\/strong><\/p>\n<p>Os belgas \u2013 que jogaram com uma inusitada camisa azul clara com bolinhas rosas \u2013 come\u00e7aram tendo uma chance. Logo aos oito minutos do primeiro tempo, Trossard arriscou da linha da grande \u00e1rea e o goleiro Diaw encaixou.\u00a0<\/p>\n<p>A resposta foi r\u00e1pida. Aos 12 minutos, em cruzamento para a \u00e1rea, o goleiro Courtois errou o tempo da bola, que ficou limpa para Ismaila Sarr. Desequilibrado, o atacante senegal\u00eas tocou, mas na trave.\u00a0<\/p>\n<p><strong>PGR defende que Bolsonaro seja mantido em pris\u00e3o domiciliar<\/strong><\/p>\n<p><strong>Policial cient\u00edfico Diocezar Monteiro Maidana morre aos 48 anos<\/strong><\/p>\n<p>A bola continuou na pequena \u00e1rea e Sarr perdeu novamente, batendo na rede pelo lado de fora. Aos 16, nova chance, Gana Gueye chutou de fora da \u00e1rea. Dessa vez, Courtois encaixou sem dar rebote.<\/p>\n<p>O predom\u00ednio de Senegal era t\u00e3o vis\u00edvel que o gol era uma quest\u00e3o de tempo. Enfim, aos 24 minutos, em cruzamento para a \u00e1rea, Ismaila Sarr cabeceou na trave \u00e0 esquerda de Courtois. No rebote, Diarra completou para as redes: 1 a 0. O placar fazia justi\u00e7a ao maior volume de jogo da sele\u00e7\u00e3o africana.<\/p>\n<p>O time do t\u00e9cnico Rudi Garcia n\u00e3o conseguiu reagir e Senegal continuou mandando na partida. Aos 36 minutos, depois de uma triangula\u00e7\u00e3o r\u00e1pida, Man\u00e9 apareceu na \u00e1rea, finalizando no meio do gol, onde estava Courtois, que fez a defesa.<\/p>\n<p>O p\u00fablico no est\u00e1dio se animou aos 42 minutos, quando o ponta-esquerda belga Doku recebeu de De Bruyne e chutou para gol. A bola desviou na zaga e deu trabalho para o goleiro Diaw.\u00a0<\/p>\n<p><strong>Cacique Raoni volta para unidade de terapia intensiva<\/strong><\/p>\n<p><strong>Em 2025, 16 mulheres foram v\u00edtimas de crimes virtuais por dia no RJ<\/strong><\/p>\n<p>Aos 44, em um chute forte de De Cuyper, de fora da \u00e1rea, o goleiro espalmou a corner. Pressionando mais, a B\u00e9lgica terminou o primeiro tempo esperan\u00e7osa de conseguir o empate no segundo tempo.<\/p>\n<p>A equipe do t\u00e9cnico Pape Thiaw voltou diferente do vesti\u00e1rio. Aos 5 minutos, Ismaila Sarr foi lan\u00e7ado, entrou na \u00e1rea e fuzilou o goleiro Courtois, marcando mais um gol e chegando ao placar de 2 a 0.<\/p>\n<p>As substitui\u00e7\u00f5es do t\u00e9cnico Rudi Garcia, tirando De Bruyne e Doku, deixaram a B\u00e9lgica melhor. A entrada de Lukaku no lugar de De Ketelaere no ataque era outro sinal de que algo poderia acontecer. Tielemans acertou a rede, pelo lado de fora. Lukebakio arriscou um chute com curva, mas para fora.\u00a0<\/p>\n<p>Foi o centroavante quem conseguiu diminuir a contagem: aos 40 minutos do segundo tempo, em um cruzamento rasteiro, Lukaku se antecipou \u00e0 zaga e desviou para o gol: 2 a 1.\u00a0\u00a0<\/p>\n<p>Aos 43 minutos, em um levantamento para a \u00e1rea, o goleiro Diaw saiu atabalhoado e Tielemans cabeceou para a meta vazia: 2 a 2. A B\u00e9lgica empatava um jogo perdido e ia para a prorroga\u00e7\u00e3o revigorada.<\/p>\n<h2>Prorroga\u00e7\u00e3o e gol salvador<\/h2>\n<p>No tempo extra, o t\u00e9cnico de Senegal tirou o maior \u00eddolo local, Sadio Man\u00e9, e colocou Nicolas Jackson. Na primeira etapa, muito medo e receio das duas sele\u00e7\u00f5es em se expor a contra-ataques.\u00a0<\/p>\n<p>Dessa forma, foram 15 minutos sem emo\u00e7\u00f5es. A diferen\u00e7a \u00e9 que a B\u00e9lgica passou a ter mais posse de bola do que seu rival e a frequentar o campo de ataque constantemente.<\/p>\n<p>No segundo tempo da prorroga\u00e7\u00e3o, Mbaye desperdi\u00e7ou uma \u00f3tima chance de fazer o gol da vit\u00f3ria. Bara Ndiaye arriscou e Courtois encaixou firme o chute rasteiro.\u00a0<\/p>\n<p>O belga Lukebakio teve a bola do jogo no finalzinho: recebeu um passe livre dentro da \u00e1rea, ajeitou e chutou forte: a bola pegou no travess\u00e3o do goleiro Diaw e foi para fora.<\/p>\n<p><strong>O VAR, no entanto, interferiu no lance. Acusou um p\u00eanalti ocorrido anteriormente, quando Camara cal\u00e7ou Tielemans na \u00e1rea, e o juiz hondurenho Said Mart\u00ednez foi ao v\u00eddeo confirmando a penalidade para os belgas aos 120 minutos.\u00a0<\/strong><\/p>\n<p><strong>Tielemans deslocou o goleiro e fez o gol da vit\u00f3ria: 3 a 2.\u00a0<\/strong><\/p>\n<p>A maior virada da Copa de 2026 aconteceu sob os olhos de 67 mil espectadores em Seattle.\u00a0<\/p>\n<p>A nova gera\u00e7\u00e3o belga vai para as oitavas de final e enfrentar\u00e1 na segunda-feira (6), \u00e0s 21h, o vencedor de Estados Unidos e B\u00f3snia Herzegovina para continuar fazendo hist\u00f3ria.<\/p>\n<h2>Ficha t\u00e9cnica<\/h2>\n<p>Quarta-feira, 1\u00ba de julho de 2026<\/p>\n<p>B\u00c9LGICA 3 x 2 SENEGAL<\/p>\n<p>Local: Seattle (Estados Unidos)<\/p>\n<p>Juiz: Said Mart\u00ednez (Honduras)<\/p>\n<p>P\u00fablico: 66.925<\/p>\n<p>B\u00e9lgica: Courtois, Castagne, Mechele, Theate e De Cuyper (Meunier); Tielemans, Vanaken (Moreira), Trossard (Onana), De Bruyne (Raskin) e Doku (Lukebakio); De Ketelaere (Lukaku). T: Rudi Garcia.<\/p>\n<p>Senegal: Diaw, Diatta, Ciss, Niakhat\u00e9 e Jakobs (Diouf); Habib Diarra (Pape Sarr), Idrissa Gueye (Bara Ndiaye) e Pape Gueye (Camara); Iliman Ndiaye (Mbaye), Ismaila Sarr e Man\u00e9 (Jackson). T: Pape Thiaw.<\/p>\n<p>Gols: No 1\u00ba tempo: Habib Diarra (24). No 2\u00ba tempo: Ismaila Sarr (5). No 2\u00ba tempo: Lukaku (40) e Tielemans (43). No 2\u00ba tempo da prorroga\u00e7\u00e3o: Tielemans (p\u00ean.) (20).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pela segunda fase da Copa do Mundo, a B\u00e9lgica \u2013 primeiro lugar no Grupo G&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-46098","post","type-post","status-publish","format-standard","hentry","category-jogos-ao-vivo"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/46098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=46098"}],"version-history":[{"count":0,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/posts\/46098\/revisions"}],"wp:attachment":[{"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=46098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=46098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipatingafc.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=46098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}